{"id":969,"date":"2022-08-09T15:48:21","date_gmt":"2022-08-09T18:48:21","guid":{"rendered":"https:\/\/tandemsd.com\/?p=969"},"modified":"2026-04-14T09:55:58","modified_gmt":"2026-04-14T12:55:58","slug":"opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas","status":"publish","type":"post","link":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/","title":{"rendered":"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light has-parallax\" style=\"min-height:430px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><div class=\"wp-block-cover__image-background wp-image-3005 has-parallax lazyload\" style=\"background-position:50% 50%;background-image:inherit\" data-bg-image=\"url(https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\">Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color\" style=\"margin-top:var(--wp--preset--spacing--50)\">El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja: &#8216;Yo nunca estuve de acuerdo con esta decisi\u00f3n&#8217;. \u00bfC\u00f3mo evitar estos dos espec\u00edmenes de la vida corporativa?<\/p>\n\n\n\n<p>Reuni\u00f3n de direcci\u00f3n. Se est\u00e1 por tomar una decisi\u00f3n importante. De pronto, alguien, que no se sabe bien qu\u00e9 rol cumple en la sala, emite una opini\u00f3n: &#8216;\u00bfEstamos seguros de que ese camino es el mejor? Yo no estoy tan seguro&#8217;. Sus palabras introducen dudas en lo que parec\u00eda una decisi\u00f3n tomada.<\/p>\n\n\n\n<p>En la misma sala, uno de los directores no emiti\u00f3 palabra en toda la reuni\u00f3n. No parece muy convencido. Estoy contento que no se opuso, pero, si avanzamos con la decisi\u00f3n, \u00bfcu\u00e1l ser\u00e1 su nivel de compromiso con la ejecuci\u00f3n? \u00bfApoyar\u00e1 la implementaci\u00f3n o ser\u00e1 el primero en decir: &#8216;Yo nunca estuve de acuerdo&#8217;?<\/p>\n\n\n\n<p>Las organizaciones tienen anticuerpos contra la aprobaci\u00f3n \u00e1gil de proyectos. Son mecanismos que los bur\u00f3cratas corporativos emplean para demorar las cosas o impedir que se implementen las decisiones que no los favorecen.<\/p>\n\n\n\n<p><strong>Opin\u00f3logos:<\/strong>&nbsp;doctores en opini\u00f3n y profesionales del punto de vista, creen que pueden expresar su opini\u00f3n a\u00fan cuando nadie se la pidi\u00f3. Sus intervenciones causan estragos en el avance de proyectos. En general, son personas respetadas en alg\u00fan campo, pero ellos creen que esa expertise los autoriza a opinar tambi\u00e9n sobre todos los dem\u00e1s. \u00bfTienen la autoridad formal para hacerlo?<\/p>\n\n\n\n<p><strong>Opositores silenciosos:<\/strong>&nbsp;en el polo opuesto a los opin\u00f3logos est\u00e1n los que ejercen una oposici\u00f3n silenciosa. No hablan, pero tampoco avanzan. Siempre se los ve pasivos en las reuniones. No apoyan ni cuestionan. Nadie sabe qu\u00e9 piensan. En general, no quieren asumir el costo pol\u00edtico de oponerse. Por eso, esperan a que los dem\u00e1s hablen antes. O dejan pasar el tema, sabiendo que igualmente no van a ejecutar lo que se decida en la sala.<\/p>\n\n\n\n<p>Ambos perfiles son igualmente da\u00f1inos. Ambos generan demoras, desv\u00edan recursos e introducen confusi\u00f3n en los procesos de aprobaci\u00f3n de proyectos. Y, lo peor, es que muchas veces estos perfiles son generados por las mismas organizaciones.<\/p>\n\n\n\n<p class=\"has-ast-global-color-2-color has-text-color\"><strong>C\u00f3mo los generamos<\/strong><\/p>\n\n\n\n<p>En general, el opin\u00f3logo no tiene la culpa. Opina porque se lo invit\u00f3 a la reuni\u00f3n y se le da la palabra. Estas son las fuentes m\u00e1s frecuentes de generaci\u00f3n de opin\u00f3logos:<\/p>\n\n\n\n<p><strong>Invitaciones difusas:\u00a0<\/strong>\u00bfestuvo alguna vez en una reuni\u00f3n sin tener en claro para qu\u00e9 estaba ah\u00ed? \u00bfO cu\u00e1l es el aporte que se esperaba de usted? Tenemos muchas reuniones, demasiadas, y nuestra participaci\u00f3n en ellas debe ser muy bien evaluada y elegida para maximizar nuestro aporte. Sobre todo, poder participar en las reuniones que de verdad agregan valor y en las que nuestro aporte es relevante. El m\u00e1ximo valor que se puede obtener del tiempo aplicado a una reuni\u00f3n se da cuando la usamos para tomar decisiones. En ese caso, todos los que participan deben cumplir alg\u00fan rol: proveer input, advertir sobre riesgos potenciales, evaluar la factibilidad de una implementaci\u00f3n, proponer alternativas. Nadie que no tenga un rol claro que cumplir deber\u00eda entrar a la sala. Nadie.<\/p>\n\n\n\n<p><strong>Invitaciones reenviadas:<\/strong>&nbsp;recibimos una invitaci\u00f3n a una reuni\u00f3n. Pero, como no podemos asistir, la reenviamos porque creemos que ser\u00eda bueno que otro participe o para que nos reemplace. Tal vez nosotros s\u00ed ten\u00edamos un rol en la decisi\u00f3n a tomar y capacidad para tomarla, pero el otro no. Cuando se le pregunte al reemplazante su opini\u00f3n, generar\u00e1 una necesidad de consulta y demorar\u00e1 la decisi\u00f3n. Si nos invitan a una reuni\u00f3n, tenemos s\u00f3lo tres alternativas: 1) ir; 2) delegar con plena potestad de decisi\u00f3n a otro; 3) no ir y renunciar a tener voz y voto en la decisi\u00f3n. No ir y adem\u00e1s no estar de acuerdo con la decisi\u00f3n, no es una opci\u00f3n.<\/p>\n\n\n\n<p><strong>Invitar para que se exponga o aprenda:<\/strong>&nbsp;a veces, se invita a j\u00f3venes profesionales o a altos potenciales a reuniones para que aprendan y se desarrollen. Tal vez sea cierto. Pero, \u00bfcu\u00e1l es el costo de sumar a una persona a un momento clave de decisi\u00f3n? Su sola participaci\u00f3n puede entorpecer un proceso cr\u00edtico para la empresa. Las reuniones de decisi\u00f3n deben tener pocos participantes. Existen muchos n\u00fameros m\u00e1gicos respecto a la cantidad \u00f3ptima de participantes (cinco, siete, nueve) pero sin duda menos que diez. M\u00e1s que eso genera demoras, entorpece y no facilita el proceso de decisi\u00f3n. Sin duda, no es el mejor momento para foguear a un joven profesional.<\/p>\n\n\n\n<p><strong>Emails con copia sin explicaci\u00f3n:<\/strong>&nbsp;es la versi\u00f3n digital de la invitaci\u00f3n difusa a reuniones. Si estamos en copia de una cadena de emails, podemos preguntarnos: &#8216;\u00bfSi estoy en copia y no contesto, apruebo el contenido? \u00bfY si estoy en copia oculta? \u00bfY si me lo reenv\u00edan?&#8217;. Lo m\u00e1s frecuente es que terminemos leyendo esas largas cadenas y opinando sobre temas donde poco podemos aportar.<\/p>\n\n\n\n<p><strong>FYI (For Your Info):<\/strong>\u00a0las siglas FYI (o su versi\u00f3n en espa\u00f1ol PVI, Para Vuestra Informaci\u00f3n) son el arma m\u00e1s potente de generaci\u00f3n de opin\u00f3logos. No s\u00f3lo obliga a leer todo el correo sin saber para qu\u00e9, sino que tampoco queda claro si se pide una acci\u00f3n espec\u00edfica. \u00bfY qu\u00e9 pasa si no contestamos? \u00bfNos estamos comprometiendo a algo? El FYI dispara muchas ambig\u00fcedades, genera dudas sobre roles y falsas expectativas. Mejor evitarlo.<\/p>\n\n\n\n<p>Mientras que el error con los opin\u00f3logos es darles lugar para opinar donde no deber\u00edan tenerlo, con los opositores silenciosos, el problema es el contrario: no los exponemos ni los obligamos a salir de sus madrigueras.<\/p>\n\n\n\n<p>El supuesto base, claramente falaz, es que si la persona no se opuso abiertamente, se comprometi\u00f3 a apoyar. \u00bfQui\u00e9n dijo que el que calla otorga? Esto no funciona as\u00ed en la toma de decisiones. El silencio no es aprobaci\u00f3n y mucho menos compromiso. Por lo general, el silencio responde a que la persona consider\u00f3 que el costo de oponerse era mayor al de comprometerse.<\/p>\n\n\n\n<p>Asumir que levantar la mano tiene igual costo que no hacerlo es falso. Los opositores silenciosos prefieren generalmente esperar para ver cu\u00e1ndo hablar, o esperar que otro hable primero, o no hablar nunca. Igual, no se har\u00e1.<\/p>\n\n\n\n<p>No exigir compromiso expreso es una falta grave al momento de buscar un acuerdo. Si queremos acuerdos que se respeten, dediquemos el tiempo en la reuni\u00f3n a expresar estos acuerdos y buscar la validaci\u00f3n expl\u00edcita.<\/p>\n\n\n\n<p class=\"has-ast-global-color-2-color has-text-color\"><strong>C\u00f3mo evitar opin\u00f3logos y silenci\u00f3logos<\/strong><\/p>\n\n\n\n<p>Para evitar opin\u00f3logos y silenci\u00f3logos, es posible seguir una serie de pasos que aseguren que los puntos de vista de las personas que pueden aportar valor a las decisiones se expresen a tiempo.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Identifique sus decisiones m\u00e1s importantes.<\/strong>&nbsp;Focal\u00edcese s\u00f3lo en las decisiones clave que impactan sus objetivos. No pierda tiempo.<\/li>\n\n\n\n<li><strong>Entienda qu\u00e9 decisiones se deben tomar en cada reuni\u00f3n.<\/strong>&nbsp;Minimice las reuniones sin decisiones y ponga el foco en las decisiones cr\u00edticas.<\/li>\n\n\n\n<li><strong>Defina roles claros para cada decisi\u00f3n.<\/strong>&nbsp;Al menos qui\u00e9n participa y qui\u00e9n no. Con el que no participa, expl\u00edquele por qu\u00e9. Con el que s\u00ed participa, expl\u00edquele c\u00f3mo.<\/li>\n\n\n\n<li><strong>Invite s\u00f3lo a los que tengan alg\u00fan rol.<\/strong>&nbsp;No permita el tr\u00e1fico de invitaciones. Las invitaciones no son transferibles ni son entradas al portador.<\/li>\n\n\n\n<li><strong>H\u00e1galos hablar y comprometerse en la reuni\u00f3n.<\/strong>&nbsp;Dedique en la agenda tiempo para validar los acuerdos, y h\u00e1galo expresamente. Es la clave.<\/li>\n<\/ol>\n\n\n\n<p>Seguir estos pasos no garantiza el \u00e9xito, pero reducir\u00e1 significativamente estos males logrando procesos de decisi\u00f3n m\u00e1s \u00e1giles y m\u00e1s confiables. Un proceso de decisi\u00f3n sin opin\u00f3logos y sin opositores silenciosos terminar\u00e1 d\u00e1ndole a su negocio mayor velocidad de respuesta, le permitir\u00e1 dormir tranquilo ya que no aparecer\u00e1n sorpresas ni retrabajos en la ejecuci\u00f3n y podr\u00e1 sin duda impactar con acuerdos sostenidos los objetivos clave del negocio. <\/p>\n\n\n\n<p><strong>Gast\u00f3n Francese<br><\/strong>Socio de Tandem.<br><a href=\"mailto:ew@tandemsd.com\">gf@tandemsd.com<\/a><\/p>\n  <div class=\"related-post grid\">\r\n        <div class=\"headline\">Art\u00edculos Relacionados<\/div>\r\n    <div class=\"post-list \">\r\n\r\n            <div class=\"item\">\r\n          \r\n  <a class=\"title post_title\"  title=\"Estrategia para el desayuno: \u00bfc\u00f3mo asegurar que una estrategia se transforme en acci\u00f3n y en resultados?\" href=\"https:\/\/tandemsd.com\/es\/estrategia-para-el-desayuno-como-asegurar-que-una-estrategia-se-transforme-en-accion-y-en-resultados\/\">\r\n        Estrategia para el desayuno: \u00bfc\u00f3mo asegurar que una estrategia se transforme en acci\u00f3n y en resultados?  <\/a>\r\n\r\n  <p class=\"excerpt post_excerpt\">\r\n    Uno de los m\u00e1ximos desaf\u00edos de los ejecutivos est\u00e1 vinculado a c\u00f3mo hacer para que una nueva estrategia se impregne en la organizaci\u00f3n, sea incorporada de manera simple por la <a class=\"read-more\" href=\"https:\/\/tandemsd.com\/es\/estrategia-para-el-desayuno-como-asegurar-que-una-estrategia-se-transforme-en-accion-y-en-resultados\/\"> \u00bb<\/a>  <\/p>\r\n        <\/div>\r\n              <div class=\"item\">\r\n          \r\n  <a class=\"title post_title\"  title=\"Las decisiones antes que el c\u00f3digo (o c\u00f3mo despertar de la matrix)\" href=\"https:\/\/tandemsd.com\/es\/las-decisiones-antes-que-el-codigo\/\">\r\n        Las decisiones antes que el c\u00f3digo (o c\u00f3mo despertar de la matrix)  <\/a>\r\n\r\n  <p class=\"excerpt post_excerpt\">\r\n    El acceso a la informaci\u00f3n y la capacidad computacional para procesarla deslumbra a las empresas. Sin embargo, para aprovechar su potencial en los negocios es clave entender por d\u00f3nde empezar, <a class=\"read-more\" href=\"https:\/\/tandemsd.com\/es\/las-decisiones-antes-que-el-codigo\/\"> \u00bb<\/a>  <\/p>\r\n        <\/div>\r\n      \r\n  <\/div>\r\n\r\n  <script>\r\n      <\/script>\r\n  <style>\r\n    .related-post {}\r\n\r\n    .related-post .post-list {\r\n      text-align: left;\r\n          }\r\n\r\n    .related-post .post-list .item {\r\n      margin: 10px;\r\n      padding: 0px;\r\n          }\r\n\r\n    .related-post .headline {\r\n      font-size: 24px !important;\r\n      color: #ff6e2e !important;\r\n          }\r\n\r\n    .related-post .post-list .item .post_thumb {\r\n      max-height: 220px;\r\n      margin: 10px 0px;\r\n      padding: 0px;\r\n      display: block;\r\n          }\r\n\r\n    .related-post .post-list .item .post_title {\r\n      font-size: 18px;\r\n      color: #006dda;\r\n      margin: 10px 0px;\r\n      padding: 0px;\r\n      display: block;\r\n      text-decoration: none;\r\n          }\r\n\r\n    .related-post .post-list .item .post_excerpt {\r\n      font-size: 15px;\r\n      color: #1f175a;\r\n      margin: 10px 0px;\r\n      padding: 0px;\r\n      display: block;\r\n      text-decoration: none;\r\n          }\r\n\r\n    @media only screen and (min-width: 1024px) {\r\n      .related-post .post-list .item {\r\n        width: 45%;\r\n      }\r\n    }\r\n\r\n    @media only screen and (min-width: 768px) and (max-width: 1023px) {\r\n      .related-post .post-list .item {\r\n        width: 90%;\r\n      }\r\n    }\r\n\r\n    @media only screen and (min-width: 0px) and (max-width: 767px) {\r\n      .related-post .post-list .item {\r\n        width: 90%;\r\n      }\r\n    }\r\n\r\n      <\/style>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja: &#8216;Yo nunca estuve de acuerdo con esta decisi\u00f3n&#8217;. \u00bfC\u00f3mo evitar estos dos espec\u00edmenes de la vida corporativa?<\/p>\n  <div class=\"related-post grid\">\r\n        <div class=\"headline\">Art\u00edculos Relacionados<\/div>\r\n    <div class=\"post-list \">\r\n\r\n            <div class=\"item\">\r\n          \r\n  <a class=\"title post_title\"  title=\"Estrategia para el desayuno: \u00bfc\u00f3mo asegurar que una estrategia se transforme en acci\u00f3n y en resultados?\" href=\"https:\/\/tandemsd.com\/es\/estrategia-para-el-desayuno-como-asegurar-que-una-estrategia-se-transforme-en-accion-y-en-resultados\/\">\r\n        Estrategia para el desayuno: \u00bfc\u00f3mo asegurar que una estrategia se transforme en acci\u00f3n y en resultados?  <\/a>\r\n\r\n  <p class=\"excerpt post_excerpt\">\r\n    Uno de los m\u00e1ximos desaf\u00edos de los ejecutivos est\u00e1 vinculado a c\u00f3mo hacer para que una nueva estrategia se impregne en la organizaci\u00f3n, sea incorporada de manera simple por la <a class=\"read-more\" href=\"https:\/\/tandemsd.com\/es\/estrategia-para-el-desayuno-como-asegurar-que-una-estrategia-se-transforme-en-accion-y-en-resultados\/\"> \u00bb<\/a>  <\/p>\r\n        <\/div>\r\n              <div class=\"item\">\r\n          \r\n  <a class=\"title post_title\"  title=\"C\u00f3mo dise\u00f1ar organizaciones en las que se decida bien\" href=\"https:\/\/tandemsd.com\/es\/como-disenar-organizaciones-en-las-que-se-decida-bien\/\">\r\n        C\u00f3mo dise\u00f1ar organizaciones en las que se decida bien  <\/a>\r\n\r\n  <p class=\"excerpt post_excerpt\">\r\n    Las empresas son el resultado de las decisiones que toman. Es por esto por lo que revisar la forma en que se decide en una organizaci\u00f3n, resulta cr\u00edtico para lograr <a class=\"read-more\" href=\"https:\/\/tandemsd.com\/es\/como-disenar-organizaciones-en-las-que-se-decida-bien\/\"> \u00bb<\/a>  <\/p>\r\n        <\/div>\r\n      \r\n  <\/div>\r\n\r\n  <script>\r\n      <\/script>\r\n  <style>\r\n    .related-post {}\r\n\r\n    .related-post .post-list {\r\n      text-align: left;\r\n          }\r\n\r\n    .related-post .post-list .item {\r\n      margin: 10px;\r\n      padding: 0px;\r\n          }\r\n\r\n    .related-post .headline {\r\n      font-size: 24px !important;\r\n      color: #ff6e2e !important;\r\n          }\r\n\r\n    .related-post .post-list .item .post_thumb {\r\n      max-height: 220px;\r\n      margin: 10px 0px;\r\n      padding: 0px;\r\n      display: block;\r\n          }\r\n\r\n    .related-post .post-list .item .post_title {\r\n      font-size: 18px;\r\n      color: #006dda;\r\n      margin: 10px 0px;\r\n      padding: 0px;\r\n      display: block;\r\n      text-decoration: none;\r\n          }\r\n\r\n    .related-post .post-list .item .post_excerpt {\r\n      font-size: 15px;\r\n      color: #1f175a;\r\n      margin: 10px 0px;\r\n      padding: 0px;\r\n      display: block;\r\n      text-decoration: none;\r\n          }\r\n\r\n    @media only screen and (min-width: 1024px) {\r\n      .related-post .post-list .item {\r\n        width: 45%;\r\n      }\r\n    }\r\n\r\n    @media only screen and (min-width: 768px) and (max-width: 1023px) {\r\n      .related-post .post-list .item {\r\n        width: 90%;\r\n      }\r\n    }\r\n\r\n    @media only screen and (min-width: 0px) and (max-width: 767px) {\r\n      .related-post .post-list .item {\r\n        width: 90%;\r\n      }\r\n    }\r\n\r\n      <\/style>\r\n    <\/div>\r\n","protected":false},"author":1,"featured_media":3005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[107,23],"tags":[60],"class_list":["post-969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulo","category-insights-es","tag-articulo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?<\/title>\n<meta name=\"description\" content=\"El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?\" \/>\n<meta property=\"og:description\" content=\"El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/\" \/>\n<meta property=\"og:site_name\" content=\"Tandem Boosting Decisions\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-09T18:48:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T12:55:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1197\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminflux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TandemSD\" \/>\n<meta name=\"twitter:site\" content=\"@TandemSD\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminflux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/\"},\"author\":{\"name\":\"adminflux\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#\\\/schema\\\/person\\\/5bab607b668cb51b679a549f344137ef\"},\"headline\":\"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?\",\"datePublished\":\"2022-08-09T18:48:21+00:00\",\"dateModified\":\"2026-04-14T12:55:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/\"},\"wordCount\":1434,\"publisher\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tandemsd.com\\\/wp-content\\\/uploads\\\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg\",\"keywords\":[\"Art\u00edculo\"],\"articleSection\":[\"Art\u00edculo\",\"Insights\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/\",\"url\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/\",\"name\":\"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tandemsd.com\\\/wp-content\\\/uploads\\\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg\",\"datePublished\":\"2022-08-09T18:48:21+00:00\",\"dateModified\":\"2026-04-14T12:55:58+00:00\",\"description\":\"El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tandemsd.com\\\/wp-content\\\/uploads\\\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg\",\"contentUrl\":\"https:\\\/\\\/tandemsd.com\\\/wp-content\\\/uploads\\\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg\",\"width\":1197,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/\",\"name\":\"Tandem Boosting Decisions\",\"description\":\"Impacting on results\",\"publisher\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#organization\",\"name\":\"Tandem\",\"url\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tandemsd.com\\\/wp-content\\\/uploads\\\/cropped-logo20_blanco-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/tandemsd.com\\\/wp-content\\\/uploads\\\/cropped-logo20_blanco-scaled-1.jpg\",\"width\":2548,\"height\":847,\"caption\":\"Tandem\"},\"image\":{\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/TandemSD\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tandemsd\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/#\\\/schema\\\/person\\\/5bab607b668cb51b679a549f344137ef\",\"name\":\"adminflux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe210c6390d40fad173c067dc11ab87e1ed642adef7d6ffb92faaf53fea926e6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe210c6390d40fad173c067dc11ab87e1ed642adef7d6ffb92faaf53fea926e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe210c6390d40fad173c067dc11ab87e1ed642adef7d6ffb92faaf53fea926e6?s=96&d=mm&r=g\",\"caption\":\"adminflux\"},\"sameAs\":[\"https:\\\/\\\/tandemsd.com\"],\"url\":\"https:\\\/\\\/tandemsd.com\\\/es\\\/author\\\/adminflux\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?","description":"El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/","og_locale":"es_ES","og_type":"article","og_title":"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?","og_description":"El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja...","og_url":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/","og_site_name":"Tandem Boosting Decisions","article_published_time":"2022-08-09T18:48:21+00:00","article_modified_time":"2026-04-14T12:55:58+00:00","og_image":[{"width":1197,"height":800,"url":"https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg","type":"image\/jpeg"}],"author":"adminflux","twitter_card":"summary_large_image","twitter_creator":"@TandemSD","twitter_site":"@TandemSD","twitter_misc":{"Escrito por":"adminflux","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/#article","isPartOf":{"@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/"},"author":{"name":"adminflux","@id":"https:\/\/tandemsd.com\/es\/#\/schema\/person\/5bab607b668cb51b679a549f344137ef"},"headline":"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?","datePublished":"2022-08-09T18:48:21+00:00","dateModified":"2026-04-14T12:55:58+00:00","mainEntityOfPage":{"@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/"},"wordCount":1434,"publisher":{"@id":"https:\/\/tandemsd.com\/es\/#organization"},"image":{"@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg","keywords":["Art\u00edculo"],"articleSection":["Art\u00edculo","Insights"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/","url":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/","name":"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?","isPartOf":{"@id":"https:\/\/tandemsd.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/#primaryimage"},"image":{"@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg","datePublished":"2022-08-09T18:48:21+00:00","dateModified":"2026-04-14T12:55:58+00:00","description":"El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja...","breadcrumb":{"@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/#primaryimage","url":"https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg","contentUrl":"https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg","width":1197,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/tandemsd.com\/es\/opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/tandemsd.com\/es\/"},{"@type":"ListItem","position":2,"name":"Opin\u00f3logos y silenci\u00f3logos, \u00bfc\u00f3mo evitar estos dos grandes males de las empresas?"}]},{"@type":"WebSite","@id":"https:\/\/tandemsd.com\/es\/#website","url":"https:\/\/tandemsd.com\/es\/","name":"Tandem Boosting Decisions","description":"Impacting on results","publisher":{"@id":"https:\/\/tandemsd.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tandemsd.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tandemsd.com\/es\/#organization","name":"Tandem","url":"https:\/\/tandemsd.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tandemsd.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tandemsd.com\/wp-content\/uploads\/cropped-logo20_blanco-scaled-1.jpg","contentUrl":"https:\/\/tandemsd.com\/wp-content\/uploads\/cropped-logo20_blanco-scaled-1.jpg","width":2548,"height":847,"caption":"Tandem"},"image":{"@id":"https:\/\/tandemsd.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/TandemSD","https:\/\/www.linkedin.com\/company\/tandemsd\/"]},{"@type":"Person","@id":"https:\/\/tandemsd.com\/es\/#\/schema\/person\/5bab607b668cb51b679a549f344137ef","name":"adminflux","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe210c6390d40fad173c067dc11ab87e1ed642adef7d6ffb92faaf53fea926e6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe210c6390d40fad173c067dc11ab87e1ed642adef7d6ffb92faaf53fea926e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe210c6390d40fad173c067dc11ab87e1ed642adef7d6ffb92faaf53fea926e6?s=96&d=mm&r=g","caption":"adminflux"},"sameAs":["https:\/\/tandemsd.com"],"url":"https:\/\/tandemsd.com\/es\/author\/adminflux\/"}]}},"author_meta":{"display_name":"adminflux","author_link":"https:\/\/tandemsd.com\/es\/author\/adminflux\/"},"featured_img":"https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1-300x201.jpg","uagb_featured_image_src":{"full":["https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg",1197,800,false],"thumbnail":["https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1-150x150.jpg",150,150,true],"medium":["https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1-300x201.jpg",300,201,true],"medium_large":["https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1-768x513.jpg",768,513,true],"large":["https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1-1024x684.jpg",1024,684,true],"1536x1536":["https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg",1197,800,false],"2048x2048":["https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg",1197,800,false],"mailpoet_newsletter_max":["https:\/\/tandemsd.com\/wp-content\/uploads\/Opinologos-y-silenciologos-como-evitar-estos-dos-grandes-males-de-las-empresas.jpg-1.jpg",1197,800,false]},"uagb_author_info":{"display_name":"adminflux","author_link":"https:\/\/tandemsd.com\/es\/author\/adminflux\/"},"uagb_comment_info":0,"uagb_excerpt":"El opin\u00f3logo habla sin saber y retrasa decisiones que parec\u00edan tomadas. El silenci\u00f3logo nunca se opone, y despu\u00e9s se ataja: 'Yo nunca estuve de acuerdo con esta decisi\u00f3n'. \u00bfC\u00f3mo evitar estos dos espec\u00edmenes de la vida corporativa?","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/tandemsd.com\/es\/category\/insights-es\/articulo\/\" class=\"advgb-post-tax-term\">Art\u00edculo<\/a>","<a href=\"https:\/\/tandemsd.com\/es\/category\/insights-es\/\" class=\"advgb-post-tax-term\">Insights<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Art\u00edculo<\/span>","<span class=\"advgb-post-tax-term\">Insights<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/tandemsd.com\/es\/category\/insights-es\/\" class=\"advgb-post-tax-term\">Art\u00edculo<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Art\u00edculo<\/span>"]}},"comment_count":0,"relative_dates":{"created":"Publicado 4 a\u00f1os hace","modified":"Actualizado 4 semanas hace"},"absolute_dates":{"created":"Publicado el 9 agosto, 2022","modified":"Actualizado el 14 abril, 2026"},"absolute_dates_time":{"created":"Publicado el 9 agosto, 2022 3:48 pm","modified":"Actualizado el 14 abril, 2026 9:55 am"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/posts\/969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/comments?post=969"}],"version-history":[{"count":6,"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/posts\/969\/revisions"}],"predecessor-version":[{"id":6474,"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/posts\/969\/revisions\/6474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/media\/3005"}],"wp:attachment":[{"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/media?parent=969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/categories?post=969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tandemsd.com\/es\/wp-json\/wp\/v2\/tags?post=969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}